{"id":1748,"date":"2017-07-11T18:44:21","date_gmt":"2017-07-11T18:44:21","guid":{"rendered":"http:\/\/jessel.de\/365-tage-sylt\/?p=1748"},"modified":"2017-07-11T18:59:07","modified_gmt":"2017-07-11T18:59:07","slug":"besuch-im-tierheim","status":"publish","type":"post","link":"https:\/\/jessel.de\/365-tage-sylt\/besuch-im-tierheim\/","title":{"rendered":"Besuch im Tierheim"},"content":{"rendered":"<p>Hallo Kinder, heute nur ganz kurz: Der Tag beginnt grau &#8211; ich sitze lange im Ausguck, denn Wolkenl\u00fccken k\u00f6nnen jederzeit vorbei gesegelt kommen &#8211; sie kommen aber zu sp\u00e4t, leider.<\/p>\n<p>Nachmittags bin ich mit meiner schreibenden Lieblings-Kollegin Kattrin im Rahmen eines Auftrags im Sylter Tierheim bei Sandy H\u00fcbner. Sandy ist DIE Anlaufstelle auf der Insel bei Problemen mit Tieren. Sie versorgt gemeinsam mit ihren KollegInnen \u00a0zur Zeit ca. 70 Haus- und Wildtiere auf einem ca. 1 ha gro\u00dfem Gel\u00e4nde:<\/p>\n<div id=\"attachment_1749\" style=\"width: 544px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1749\" class=\"size-full wp-image-1749\" src=\"http:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/07\/L1008951.jpg\" alt=\"\" width=\"534\" height=\"800\" srcset=\"https:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/07\/L1008951.jpg 534w, https:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/07\/L1008951-200x300.jpg 200w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><p id=\"caption-attachment-1749\" class=\"wp-caption-text\">Fotos? Nein Danke!<\/p><\/div>\n<p>Was f\u00fcr ein r\u00fchrendes &#8211; und physisch und psychisch &#8211; anstrengendes Engagement&#8230;<\/p>\n<p>Als wir das Tierheim gegen 17:30 Uhr verlassen, ist mir ausgesprochen pl\u00fcmerant zumute. So f\u00fchle ich mich, wenn ich am n\u00e4chsten Tag flach liege. Mein urspr\u00fcngliches Vorhaben, gegen Abend am Strand noch Fotos zu machen, knicke ich mal lieber.<\/p>\n<p>Liege um 20:30 Uhr im Bett, schreibe eben noch diesen Blog, und hoffe mal das Beste f\u00fcr morgen. Gute Nacht in die Runde!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hallo Kinder, heute nur ganz kurz: Der Tag beginnt grau &#8211; ich sitze lange im Ausguck, denn Wolkenl\u00fccken k\u00f6nnen jederzeit vorbei gesegelt kommen &#8211; sie kommen aber zu sp\u00e4t, leider. Nachmittags bin ich mit meiner schreibenden Lieblings-Kollegin Kattrin im Rahmen eines Auftrags im Sylter Tierheim bei Sandy H\u00fcbner. Sandy ist DIE Anlaufstelle auf der Insel bei Problemen mit Tieren. Sie versorgt gemeinsam mit ihren KollegInnen \u00a0zur Zeit ca. 70 Haus-&hellip;<\/p>\n","protected":false},"author":2,"featured_media":1750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,39,28,3,46,40,31],"tags":[],"class_list":["post-1748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alle-bilder","category-arbeit","category-haeuser","category-menschen","category-sommer","category-tiere","category-tinnum"],"jetpack_featured_media_url":"https:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/07\/L1008993.jpg","_links":{"self":[{"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/posts\/1748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/comments?post=1748"}],"version-history":[{"count":3,"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/posts\/1748\/revisions"}],"predecessor-version":[{"id":1753,"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/posts\/1748\/revisions\/1753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/media\/1750"}],"wp:attachment":[{"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/media?parent=1748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/categories?post=1748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/tags?post=1748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}