{"id":2056,"date":"2017-08-09T19:53:29","date_gmt":"2017-08-09T19:53:29","guid":{"rendered":"http:\/\/jessel.de\/365-tage-sylt\/?p=2056"},"modified":"2017-08-09T19:53:29","modified_gmt":"2017-08-09T19:53:29","slug":"ich-kann-so-nicht-arbeiten","status":"publish","type":"post","link":"https:\/\/jessel.de\/365-tage-sylt\/ich-kann-so-nicht-arbeiten\/","title":{"rendered":"Ich kann so nicht arbeiten!"},"content":{"rendered":"<p>Geahnt hatte ichs ja. Zuhause angekommen, schmeisse ich dem Mac an und mich trifft der Schlag, wer alles etwas von mir will: Bildauswahl hier, Fahrt nach D\u00e4nemark da, Terminplanung hier, Rechnungen schreiben da&#8230; etc. pp.. Gleichzeitig entwickelt sich draussen, nach einem tr\u00fcben fr\u00fchen Morgen, ein veritables Nordseewetterchen&#8230; meine alte, mir wohl bekannte Schw\u00e4che kommt wieder durch: Ich kann(!) nicht(!) arbeiten(!), wenn ich auf diversen Hochzeiten tanzen soll &#8211; bin dann schlichtweg nicht fokussiert.<\/p>\n<p>Egal &#8211; vormittags schaffe ich immerhin vier Rechnungen, eine Bildauswahl und sogar ein Telefonat, nachmittags geht&#8217;s ab mit dem Rad in den Sylter Osten. Es herbstelt! Wolkentraumschiffe segeln bei reichlich 6-7 Windst\u00e4rken wie Zeppeline \u00fcber mich hinweg, und ich verankere mich zun\u00e4chst im Dunstkreis der Keitumer Kirche:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2057\" src=\"http:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/08\/L1006360.jpg\" alt=\"\" width=\"1204\" height=\"800\" srcset=\"https:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/08\/L1006360.jpg 1204w, https:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/08\/L1006360-300x199.jpg 300w, https:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/08\/L1006360-768x510.jpg 768w, https:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/08\/L1006360-1024x680.jpg 1024w\" sizes=\"auto, (max-width: 1204px) 100vw, 1204px\" \/><\/p>\n<p>Dieses Foto bes\u00e4nftigt mich schon mal. Das n\u00e4chste aber noch mehr, denn diesmal passen Licht und Wolken perfekt. Mein Kalender-Verleger wird feuchte Augen bekommen:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2060\" src=\"http:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/08\/L1006363.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/08\/L1006363.jpg 1200w, https:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/08\/L1006363-300x200.jpg 300w, https:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/08\/L1006363-768x512.jpg 768w, https:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/08\/L1006363-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Ich lasse mich vom Wind noch bis Morsum treiben, aber noch vor 20 Uhr verabschiedet sich die Sonne hinter einer Wolkenbank, und das wars dann f\u00fcr heute:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2058\" src=\"http:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/08\/L1006376.jpg\" alt=\"\" width=\"1204\" height=\"800\" srcset=\"https:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/08\/L1006376.jpg 1204w, https:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/08\/L1006376-300x199.jpg 300w, https:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/08\/L1006376-768x510.jpg 768w, https:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/08\/L1006376-1024x680.jpg 1024w\" sizes=\"auto, (max-width: 1204px) 100vw, 1204px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Geahnt hatte ichs ja. Zuhause angekommen, schmeisse ich dem Mac an und mich trifft der Schlag, wer alles etwas von mir will: Bildauswahl hier, Fahrt nach D\u00e4nemark da, Terminplanung hier, Rechnungen schreiben da&#8230; etc. pp.. Gleichzeitig entwickelt sich draussen, nach einem tr\u00fcben fr\u00fchen Morgen, ein veritables Nordseewetterchen&#8230; meine alte, mir wohl bekannte Schw\u00e4che kommt wieder durch: Ich kann(!) nicht(!) arbeiten(!), wenn ich auf diversen Hochzeiten tanzen soll &#8211; bin dann&hellip;<\/p>\n","protected":false},"author":2,"featured_media":2059,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,22,46,40],"tags":[],"class_list":["post-2056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alle-bilder","category-morsum","category-sommer","category-tiere"],"jetpack_featured_media_url":"https:\/\/jessel.de\/365-tage-sylt\/wp-content\/uploads\/2017\/08\/L1006392.jpg","_links":{"self":[{"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/posts\/2056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/comments?post=2056"}],"version-history":[{"count":1,"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/posts\/2056\/revisions"}],"predecessor-version":[{"id":2061,"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/posts\/2056\/revisions\/2061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/media\/2059"}],"wp:attachment":[{"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/media?parent=2056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/categories?post=2056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jessel.de\/365-tage-sylt\/wp-json\/wp\/v2\/tags?post=2056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}